{"id":223,"count":1,"description":"","link":"https:\/\/www.viratsteel.in\/blog\/category\/tool-steel-india\/","name":"tool steel India","slug":"tool-steel-india","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.viratsteel.in\/blog\/wp-json\/wp\/v2\/categories\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viratsteel.in\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.viratsteel.in\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.viratsteel.in\/blog\/wp-json\/wp\/v2\/posts?categories=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}